{"id":3862,"date":"2022-04-25T10:34:05","date_gmt":"2022-04-25T17:34:05","guid":{"rendered":"https:\/\/elementary.sd42.ca\/yennadon\/?post_type=tribe_events&#038;p=3862"},"modified":"2022-04-25T10:34:05","modified_gmt":"2022-04-25T17:34:05","slug":"arms-butterfly-presentation-annex","status":"publish","type":"tribe_events","link":"https:\/\/elementary.sd42.ca\/yennadon\/event\/arms-butterfly-presentation-annex\/","title":{"rendered":"ARMS Butterfly Presentation &#8211; Annex"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":9,"featured_media":0,"template":"","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_tribe_events_status":"","_tribe_events_status_reason":"","footnotes":""},"tags":[],"tribe_events_cat":[],"class_list":["post-3862","tribe_events","type-tribe_events","status-publish","entry"],"_links":{"self":[{"href":"https:\/\/elementary.sd42.ca\/yennadon\/wp-json\/wp\/v2\/tribe_events\/3862","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elementary.sd42.ca\/yennadon\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/elementary.sd42.ca\/yennadon\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/elementary.sd42.ca\/yennadon\/wp-json\/wp\/v2\/users\/9"}],"version-history":[{"count":1,"href":"https:\/\/elementary.sd42.ca\/yennadon\/wp-json\/wp\/v2\/tribe_events\/3862\/revisions"}],"predecessor-version":[{"id":3863,"href":"https:\/\/elementary.sd42.ca\/yennadon\/wp-json\/wp\/v2\/tribe_events\/3862\/revisions\/3863"}],"wp:attachment":[{"href":"https:\/\/elementary.sd42.ca\/yennadon\/wp-json\/wp\/v2\/media?parent=3862"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elementary.sd42.ca\/yennadon\/wp-json\/wp\/v2\/tags?post=3862"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/elementary.sd42.ca\/yennadon\/wp-json\/wp\/v2\/tribe_events_cat?post=3862"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}