{"id":1695,"date":"2019-09-13T12:21:36","date_gmt":"2019-09-13T19:21:36","guid":{"rendered":"https:\/\/elementary.sd42.ca\/yennadon\/?post_type=tribe_events&#038;p=1695"},"modified":"2019-09-13T12:21:36","modified_gmt":"2019-09-13T19:21:36","slug":"pac-meeting-11","status":"publish","type":"tribe_events","link":"https:\/\/elementary.sd42.ca\/yennadon\/event\/pac-meeting-11\/","title":{"rendered":"PAC Meeting"},"content":{"rendered":"<p>in Library<\/p>\n","protected":false},"excerpt":{"rendered":"<p>in Library<\/p>\n","protected":false},"author":9,"featured_media":0,"template":"","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_tribe_events_status":"","_tribe_events_status_reason":"","footnotes":""},"tags":[],"tribe_events_cat":[],"class_list":["post-1695","tribe_events","type-tribe_events","status-publish","entry"],"_links":{"self":[{"href":"https:\/\/elementary.sd42.ca\/yennadon\/wp-json\/wp\/v2\/tribe_events\/1695","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elementary.sd42.ca\/yennadon\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/elementary.sd42.ca\/yennadon\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/elementary.sd42.ca\/yennadon\/wp-json\/wp\/v2\/users\/9"}],"version-history":[{"count":1,"href":"https:\/\/elementary.sd42.ca\/yennadon\/wp-json\/wp\/v2\/tribe_events\/1695\/revisions"}],"predecessor-version":[{"id":1696,"href":"https:\/\/elementary.sd42.ca\/yennadon\/wp-json\/wp\/v2\/tribe_events\/1695\/revisions\/1696"}],"wp:attachment":[{"href":"https:\/\/elementary.sd42.ca\/yennadon\/wp-json\/wp\/v2\/media?parent=1695"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elementary.sd42.ca\/yennadon\/wp-json\/wp\/v2\/tags?post=1695"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/elementary.sd42.ca\/yennadon\/wp-json\/wp\/v2\/tribe_events_cat?post=1695"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}