{"id":2263,"date":"2024-07-02T15:11:35","date_gmt":"2024-07-02T22:11:35","guid":{"rendered":"https:\/\/elementary.sd42.ca\/laityview\/event\/school-closes-for-summer-holidays-6\/"},"modified":"2024-07-02T15:11:35","modified_gmt":"2024-07-02T22:11:35","slug":"school-closes-for-summer-holidays-6","status":"publish","type":"tribe_events","link":"https:\/\/elementary.sd42.ca\/laityview\/event\/school-closes-for-summer-holidays-6\/","title":{"rendered":"School closes for summer holidays"},"content":{"rendered":"<p>School closes for summer holidays<\/p>\n","protected":false},"excerpt":{"rendered":"<p>School closes for summer holidays<\/p>\n","protected":false},"author":2,"featured_media":0,"template":"","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_tribe_events_status":"","_tribe_events_status_reason":"","footnotes":""},"tags":[],"tribe_events_cat":[4],"class_list":["post-2263","tribe_events","type-tribe_events","status-publish","tribe_events_cat-district-calendar","cat_district-calendar","entry"],"_links":{"self":[{"href":"https:\/\/elementary.sd42.ca\/laityview\/wp-json\/wp\/v2\/tribe_events\/2263","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elementary.sd42.ca\/laityview\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/elementary.sd42.ca\/laityview\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/elementary.sd42.ca\/laityview\/wp-json\/wp\/v2\/users\/2"}],"version-history":[{"count":0,"href":"https:\/\/elementary.sd42.ca\/laityview\/wp-json\/wp\/v2\/tribe_events\/2263\/revisions"}],"wp:attachment":[{"href":"https:\/\/elementary.sd42.ca\/laityview\/wp-json\/wp\/v2\/media?parent=2263"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elementary.sd42.ca\/laityview\/wp-json\/wp\/v2\/tags?post=2263"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/elementary.sd42.ca\/laityview\/wp-json\/wp\/v2\/tribe_events_cat?post=2263"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}